{"id":6865,"date":"2019-04-11T12:42:10","date_gmt":"2019-04-11T10:42:10","guid":{"rendered":"http:\/\/www.espurna.org\/?p=6865"},"modified":"2019-04-11T12:42:10","modified_gmt":"2019-04-11T10:42:10","slug":"presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia","status":"publish","type":"post","link":"https:\/\/espurna.cloud\/espurna\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia","title":{"rendered":"PRESENTACI\u00d3N DE NUESTRO PROYECTO A LOS ALUMNOS DE LA UNIVERSIDAD CAT\u00d3LICA DE VALENCIA."},"content":{"rendered":"<p><a href=\"http:\/\/www.espurna.org\/wp-content\/uploads\/2019\/04\/56957743_2157757417634156_1178825315657449472_n-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6869\" src=\"http:\/\/www.espurna.org\/wp-content\/uploads\/2019\/04\/56957743_2157757417634156_1178825315657449472_n-1-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2019\/04\/56957743_2157757417634156_1178825315657449472_n-1-300x225.jpg 300w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2019\/04\/56957743_2157757417634156_1178825315657449472_n-1-600x450.jpg 600w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2019\/04\/56957743_2157757417634156_1178825315657449472_n-1-768x576.jpg 768w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2019\/04\/56957743_2157757417634156_1178825315657449472_n-1-200x150.jpg 200w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2019\/04\/56957743_2157757417634156_1178825315657449472_n-1-150x113.jpg 150w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2019\/04\/56957743_2157757417634156_1178825315657449472_n-1.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"http:\/\/www.espurna.org\/wp-content\/uploads\/2019\/04\/56567259_2157757370967494_2206584584131313664_n-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6870\" src=\"http:\/\/www.espurna.org\/wp-content\/uploads\/2019\/04\/56567259_2157757370967494_2206584584131313664_n-1-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2019\/04\/56567259_2157757370967494_2206584584131313664_n-1-300x225.jpg 300w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2019\/04\/56567259_2157757370967494_2206584584131313664_n-1-600x450.jpg 600w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2019\/04\/56567259_2157757370967494_2206584584131313664_n-1-768x576.jpg 768w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2019\/04\/56567259_2157757370967494_2206584584131313664_n-1-200x150.jpg 200w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2019\/04\/56567259_2157757370967494_2206584584131313664_n-1-150x113.jpg 150w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2019\/04\/56567259_2157757370967494_2206584584131313664_n-1.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Los alumnos de Primero, Segundo en Cuarto de Terapia Ocupacional de la Universidad Cat\u00f3lica de Valencia nos recibieron ilusionados y disfrutaron de la Presentaci\u00f3n de nuestro Proyecto, ayer mi\u00e9rcoles 10 de abril.<\/p>\n<div class=\"text_exposed_show\">\n<p>Queremos dar las gracias a la UCV por hacer posible nuestra visita y exponer nuestro Proyecto, agradecer en especial a Francesc Ba\u00f1uls, gran amigo y profesional (Terapeuta Ocupacional; Doctor por la UCV; Profesor UCV, Coordinador C.A.R.D Capacitas, Coordinador foro Iproa CV en UCV).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los alumnos de Primero, Segundo en Cuarto de Terapia Ocupacional de la Universidad Cat\u00f3lica de Valencia nos recibieron ilusionados y disfrutaron de la Presentaci\u00f3n de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6865","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PRESENTACI\u00d3N DE NUESTRO PROYECTO A LOS ALUMNOS DE LA UNIVERSIDAD CAT\u00d3LICA DE VALENCIA. - Espurna.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/espurna.cloud\/espurna\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PRESENTACI\u00d3N DE NUESTRO PROYECTO A LOS ALUMNOS DE LA UNIVERSIDAD CAT\u00d3LICA DE VALENCIA. - Espurna.org\" \/>\n<meta property=\"og:description\" content=\"Los alumnos de Primero, Segundo en Cuarto de Terapia Ocupacional de la Universidad Cat\u00f3lica de Valencia nos recibieron ilusionados y disfrutaron de la Presentaci\u00f3n de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/espurna.cloud\/espurna\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia\" \/>\n<meta property=\"og:site_name\" content=\"Espurna.org\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-11T10:42:10+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.espurna.org\/wp-content\/uploads\/2019\/04\/56957743_2157757417634156_1178825315657449472_n-1-300x225.jpg\" \/>\n<meta name=\"author\" content=\"empleoespurna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"empleoespurna\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia\"},\"author\":{\"name\":\"empleoespurna\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#\\\/schema\\\/person\\\/3e977e600ba60638d283f4767ae199be\"},\"headline\":\"PRESENTACI\u00d3N DE NUESTRO PROYECTO A LOS ALUMNOS DE LA UNIVERSIDAD CAT\u00d3LICA DE VALENCIA.\",\"datePublished\":\"2019-04-11T10:42:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia\"},\"wordCount\":96,\"image\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.espurna.org\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/56957743_2157757417634156_1178825315657449472_n-1-300x225.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia\",\"url\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia\",\"name\":\"PRESENTACI\u00d3N DE NUESTRO PROYECTO A LOS ALUMNOS DE LA UNIVERSIDAD CAT\u00d3LICA DE VALENCIA. - Espurna.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.espurna.org\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/56957743_2157757417634156_1178825315657449472_n-1-300x225.jpg\",\"datePublished\":\"2019-04-11T10:42:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#\\\/schema\\\/person\\\/3e977e600ba60638d283f4767ae199be\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia#primaryimage\",\"url\":\"http:\\\/\\\/www.espurna.org\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/56957743_2157757417634156_1178825315657449472_n-1-300x225.jpg\",\"contentUrl\":\"http:\\\/\\\/www.espurna.org\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/56957743_2157757417634156_1178825315657449472_n-1-300x225.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PRESENTACI\u00d3N DE NUESTRO PROYECTO A LOS ALUMNOS DE LA UNIVERSIDAD CAT\u00d3LICA DE VALENCIA.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#website\",\"url\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/\",\"name\":\"Espurna.org\",\"description\":\"Atenci\u00f3n integral a personas con discapacidad intelectual\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#\\\/schema\\\/person\\\/3e977e600ba60638d283f4767ae199be\",\"name\":\"empleoespurna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g\",\"caption\":\"empleoespurna\"},\"url\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/author\\\/empleoespurna\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PRESENTACI\u00d3N DE NUESTRO PROYECTO A LOS ALUMNOS DE LA UNIVERSIDAD CAT\u00d3LICA DE VALENCIA. - Espurna.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/espurna.cloud\/espurna\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia","og_locale":"es_ES","og_type":"article","og_title":"PRESENTACI\u00d3N DE NUESTRO PROYECTO A LOS ALUMNOS DE LA UNIVERSIDAD CAT\u00d3LICA DE VALENCIA. - Espurna.org","og_description":"Los alumnos de Primero, Segundo en Cuarto de Terapia Ocupacional de la Universidad Cat\u00f3lica de Valencia nos recibieron ilusionados y disfrutaron de la Presentaci\u00f3n de...","og_url":"https:\/\/espurna.cloud\/espurna\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia","og_site_name":"Espurna.org","article_published_time":"2019-04-11T10:42:10+00:00","og_image":[{"url":"http:\/\/www.espurna.org\/wp-content\/uploads\/2019\/04\/56957743_2157757417634156_1178825315657449472_n-1-300x225.jpg","type":"","width":"","height":""}],"author":"empleoespurna","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"empleoespurna"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/espurna.cloud\/espurna\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia#article","isPartOf":{"@id":"https:\/\/espurna.cloud\/espurna\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia"},"author":{"name":"empleoespurna","@id":"https:\/\/espurna.cloud\/espurna\/#\/schema\/person\/3e977e600ba60638d283f4767ae199be"},"headline":"PRESENTACI\u00d3N DE NUESTRO PROYECTO A LOS ALUMNOS DE LA UNIVERSIDAD CAT\u00d3LICA DE VALENCIA.","datePublished":"2019-04-11T10:42:10+00:00","mainEntityOfPage":{"@id":"https:\/\/espurna.cloud\/espurna\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia"},"wordCount":96,"image":{"@id":"https:\/\/espurna.cloud\/espurna\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia#primaryimage"},"thumbnailUrl":"http:\/\/www.espurna.org\/wp-content\/uploads\/2019\/04\/56957743_2157757417634156_1178825315657449472_n-1-300x225.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/espurna.cloud\/espurna\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia","url":"https:\/\/espurna.cloud\/espurna\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia","name":"PRESENTACI\u00d3N DE NUESTRO PROYECTO A LOS ALUMNOS DE LA UNIVERSIDAD CAT\u00d3LICA DE VALENCIA. - Espurna.org","isPartOf":{"@id":"https:\/\/espurna.cloud\/espurna\/#website"},"primaryImageOfPage":{"@id":"https:\/\/espurna.cloud\/espurna\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia#primaryimage"},"image":{"@id":"https:\/\/espurna.cloud\/espurna\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia#primaryimage"},"thumbnailUrl":"http:\/\/www.espurna.org\/wp-content\/uploads\/2019\/04\/56957743_2157757417634156_1178825315657449472_n-1-300x225.jpg","datePublished":"2019-04-11T10:42:10+00:00","author":{"@id":"https:\/\/espurna.cloud\/espurna\/#\/schema\/person\/3e977e600ba60638d283f4767ae199be"},"breadcrumb":{"@id":"https:\/\/espurna.cloud\/espurna\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/espurna.cloud\/espurna\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/espurna.cloud\/espurna\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia#primaryimage","url":"http:\/\/www.espurna.org\/wp-content\/uploads\/2019\/04\/56957743_2157757417634156_1178825315657449472_n-1-300x225.jpg","contentUrl":"http:\/\/www.espurna.org\/wp-content\/uploads\/2019\/04\/56957743_2157757417634156_1178825315657449472_n-1-300x225.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/espurna.cloud\/espurna\/presentacion-de-nuestro-proyecto-a-los-alumnos-de-la-universidad-catolica-de-valencia#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/espurna.cloud\/espurna\/"},{"@type":"ListItem","position":2,"name":"PRESENTACI\u00d3N DE NUESTRO PROYECTO A LOS ALUMNOS DE LA UNIVERSIDAD CAT\u00d3LICA DE VALENCIA."}]},{"@type":"WebSite","@id":"https:\/\/espurna.cloud\/espurna\/#website","url":"https:\/\/espurna.cloud\/espurna\/","name":"Espurna.org","description":"Atenci\u00f3n integral a personas con discapacidad intelectual","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/espurna.cloud\/espurna\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/espurna.cloud\/espurna\/#\/schema\/person\/3e977e600ba60638d283f4767ae199be","name":"empleoespurna","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g","caption":"empleoespurna"},"url":"https:\/\/espurna.cloud\/espurna\/author\/empleoespurna"}]}},"_links":{"self":[{"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/posts\/6865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/comments?post=6865"}],"version-history":[{"count":0,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/posts\/6865\/revisions"}],"wp:attachment":[{"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/media?parent=6865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/categories?post=6865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/tags?post=6865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}