{"id":770,"date":"2013-02-19T16:53:07","date_gmt":"2013-02-19T16:53:07","guid":{"rendered":"http:\/\/www.espurna.org\/?p=770"},"modified":"2013-02-19T16:54:05","modified_gmt":"2013-02-19T16:54:05","slug":"noticias-desde-candanchu-segundo-dia-en-las-pistas","status":"publish","type":"post","link":"https:\/\/espurna.cloud\/espurna\/noticias-desde-candanchu-segundo-dia-en-las-pistas","title":{"rendered":"NOTICIAS DESDE CANDANCH\u00da! SEGUNDO D\u00cdA EN LAS PISTAS."},"content":{"rendered":"<p><a href=\"http:\/\/www.espurna.org\/wp-content\/uploads\/2013\/02\/la-foto-53.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-771\" title=\"la foto 5(3)\" src=\"http:\/\/www.espurna.org\/wp-content\/uploads\/2013\/02\/la-foto-53-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" srcset=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2013\/02\/la-foto-53-300x168.jpg 300w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2013\/02\/la-foto-53-600x338.jpg 600w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2013\/02\/la-foto-53.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n[juicebox gallery_id=\u00bb98&#8243;]\n<p>Los esquiadores nos mandan noticias desde Candanch\u00fa!!<\/p>\n<p>Ayer lunes, fu\u00e9 su primer d\u00eda en las pistas!<\/p>\n<p>Hicieron las pruebas iniciales para formar los diferentes grupos ( Inical &#8211; Medio y Avanzado) de cada especialidad : Esqu\u00ed N\u00f3rdico, Esqu\u00ed Alpino y Raquetas.<\/p>\n<p>Disfrutaron much\u00edsimo!<\/p>\n<p>Al mediod\u00eda comieron en el restaurante de las pistas y por la tarde regresaron al hotel.<\/p>\n<p>Por la noche celebraron el Cocktel de Bienvenida, se lo pasaron genial bailando y cantando.<\/p>\n<p>Un grupo prefri\u00f3 salir a la entrada del hotel y hacer un precioso mu\u00f1eco de nieve y un Igloo.<\/p>\n<p>Hoy Martes, de nuevo han subido a las pistas!<\/p>\n<p>Todos se han esforzado much\u00edsimo para superar el nuevo reto!<\/p>\n<p>Marta Gadea y Ana Adrover se han pasado hoy al grupo de Raquetas del Nivel Avanzado, junto a su compa\u00f1era Sandy. Han demostrado ser unas grandes campeonas. Han realizado un largo reccorido superando todas las pendientes.<\/p>\n<p>El grupo de Esqu\u00ed Alpino, han disfrutado tir\u00e1ndose por las pendientes y aprendiendo a frenar!<\/p>\n<p>Y los de N\u00f3rdico se lo han pasado en grande yendo por las huellas!<\/p>\n<p>No nos han dicho que sospresa les depara esta noche!<\/p>\n<p>Os iremos informando!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[juicebox gallery_id=\u00bb98&#8243;] Los esquiadores nos mandan noticias desde Candanch\u00fa!! Ayer lunes, fu\u00e9 su primer d\u00eda en las pistas! Hicieron las pruebas iniciales para formar los&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[36],"class_list":["post-770","post","type-post","status-publish","format-standard","hentry","category-deportes","tag-semana-blanca-2013"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NOTICIAS DESDE CANDANCH\u00da! SEGUNDO D\u00cdA EN LAS PISTAS. - Espurna.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/espurna.cloud\/espurna\/noticias-desde-candanchu-segundo-dia-en-las-pistas\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NOTICIAS DESDE CANDANCH\u00da! SEGUNDO D\u00cdA EN LAS PISTAS. - Espurna.org\" \/>\n<meta property=\"og:description\" content=\"[juicebox gallery_id=\u00bb98&#8243;] Los esquiadores nos mandan noticias desde Candanch\u00fa!! Ayer lunes, fu\u00e9 su primer d\u00eda en las pistas! Hicieron las pruebas iniciales para formar los...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/espurna.cloud\/espurna\/noticias-desde-candanchu-segundo-dia-en-las-pistas\" \/>\n<meta property=\"og:site_name\" content=\"Espurna.org\" \/>\n<meta property=\"article:published_time\" content=\"2013-02-19T16:53:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-02-19T16:54:05+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.espurna.org\/wp-content\/uploads\/2013\/02\/la-foto-53-300x168.jpg\" \/>\n<meta name=\"author\" content=\"empleoespurna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"empleoespurna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/noticias-desde-candanchu-segundo-dia-en-las-pistas#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/noticias-desde-candanchu-segundo-dia-en-las-pistas\"},\"author\":{\"name\":\"empleoespurna\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#\\\/schema\\\/person\\\/3e977e600ba60638d283f4767ae199be\"},\"headline\":\"NOTICIAS DESDE CANDANCH\u00da! SEGUNDO D\u00cdA EN LAS PISTAS.\",\"datePublished\":\"2013-02-19T16:53:07+00:00\",\"dateModified\":\"2013-02-19T16:54:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/noticias-desde-candanchu-segundo-dia-en-las-pistas\"},\"wordCount\":210,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/noticias-desde-candanchu-segundo-dia-en-las-pistas#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.espurna.org\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/la-foto-53-300x168.jpg\",\"keywords\":[\"Semana Blanca 2013\"],\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/noticias-desde-candanchu-segundo-dia-en-las-pistas#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/noticias-desde-candanchu-segundo-dia-en-las-pistas\",\"url\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/noticias-desde-candanchu-segundo-dia-en-las-pistas\",\"name\":\"NOTICIAS DESDE CANDANCH\u00da! SEGUNDO D\u00cdA EN LAS PISTAS. - Espurna.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/noticias-desde-candanchu-segundo-dia-en-las-pistas#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/noticias-desde-candanchu-segundo-dia-en-las-pistas#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.espurna.org\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/la-foto-53-300x168.jpg\",\"datePublished\":\"2013-02-19T16:53:07+00:00\",\"dateModified\":\"2013-02-19T16:54:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#\\\/schema\\\/person\\\/3e977e600ba60638d283f4767ae199be\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/noticias-desde-candanchu-segundo-dia-en-las-pistas#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/noticias-desde-candanchu-segundo-dia-en-las-pistas\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/noticias-desde-candanchu-segundo-dia-en-las-pistas#primaryimage\",\"url\":\"http:\\\/\\\/www.espurna.org\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/la-foto-53-300x168.jpg\",\"contentUrl\":\"http:\\\/\\\/www.espurna.org\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/la-foto-53-300x168.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/noticias-desde-candanchu-segundo-dia-en-las-pistas#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NOTICIAS DESDE CANDANCH\u00da! SEGUNDO D\u00cdA EN LAS PISTAS.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#website\",\"url\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/\",\"name\":\"Espurna.org\",\"description\":\"Atenci\u00f3n integral a personas con discapacidad intelectual\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#\\\/schema\\\/person\\\/3e977e600ba60638d283f4767ae199be\",\"name\":\"empleoespurna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g\",\"caption\":\"empleoespurna\"},\"url\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/author\\\/empleoespurna\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NOTICIAS DESDE CANDANCH\u00da! SEGUNDO D\u00cdA EN LAS PISTAS. - Espurna.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/espurna.cloud\/espurna\/noticias-desde-candanchu-segundo-dia-en-las-pistas","og_locale":"es_ES","og_type":"article","og_title":"NOTICIAS DESDE CANDANCH\u00da! SEGUNDO D\u00cdA EN LAS PISTAS. - Espurna.org","og_description":"[juicebox gallery_id=\u00bb98&#8243;] Los esquiadores nos mandan noticias desde Candanch\u00fa!! Ayer lunes, fu\u00e9 su primer d\u00eda en las pistas! Hicieron las pruebas iniciales para formar los...","og_url":"https:\/\/espurna.cloud\/espurna\/noticias-desde-candanchu-segundo-dia-en-las-pistas","og_site_name":"Espurna.org","article_published_time":"2013-02-19T16:53:07+00:00","article_modified_time":"2013-02-19T16:54:05+00:00","og_image":[{"url":"http:\/\/www.espurna.org\/wp-content\/uploads\/2013\/02\/la-foto-53-300x168.jpg","type":"","width":"","height":""}],"author":"empleoespurna","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"empleoespurna","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/espurna.cloud\/espurna\/noticias-desde-candanchu-segundo-dia-en-las-pistas#article","isPartOf":{"@id":"https:\/\/espurna.cloud\/espurna\/noticias-desde-candanchu-segundo-dia-en-las-pistas"},"author":{"name":"empleoespurna","@id":"https:\/\/espurna.cloud\/espurna\/#\/schema\/person\/3e977e600ba60638d283f4767ae199be"},"headline":"NOTICIAS DESDE CANDANCH\u00da! SEGUNDO D\u00cdA EN LAS PISTAS.","datePublished":"2013-02-19T16:53:07+00:00","dateModified":"2013-02-19T16:54:05+00:00","mainEntityOfPage":{"@id":"https:\/\/espurna.cloud\/espurna\/noticias-desde-candanchu-segundo-dia-en-las-pistas"},"wordCount":210,"commentCount":0,"image":{"@id":"https:\/\/espurna.cloud\/espurna\/noticias-desde-candanchu-segundo-dia-en-las-pistas#primaryimage"},"thumbnailUrl":"http:\/\/www.espurna.org\/wp-content\/uploads\/2013\/02\/la-foto-53-300x168.jpg","keywords":["Semana Blanca 2013"],"articleSection":["Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/espurna.cloud\/espurna\/noticias-desde-candanchu-segundo-dia-en-las-pistas#respond"]}]},{"@type":"WebPage","@id":"https:\/\/espurna.cloud\/espurna\/noticias-desde-candanchu-segundo-dia-en-las-pistas","url":"https:\/\/espurna.cloud\/espurna\/noticias-desde-candanchu-segundo-dia-en-las-pistas","name":"NOTICIAS DESDE CANDANCH\u00da! SEGUNDO D\u00cdA EN LAS PISTAS. - Espurna.org","isPartOf":{"@id":"https:\/\/espurna.cloud\/espurna\/#website"},"primaryImageOfPage":{"@id":"https:\/\/espurna.cloud\/espurna\/noticias-desde-candanchu-segundo-dia-en-las-pistas#primaryimage"},"image":{"@id":"https:\/\/espurna.cloud\/espurna\/noticias-desde-candanchu-segundo-dia-en-las-pistas#primaryimage"},"thumbnailUrl":"http:\/\/www.espurna.org\/wp-content\/uploads\/2013\/02\/la-foto-53-300x168.jpg","datePublished":"2013-02-19T16:53:07+00:00","dateModified":"2013-02-19T16:54:05+00:00","author":{"@id":"https:\/\/espurna.cloud\/espurna\/#\/schema\/person\/3e977e600ba60638d283f4767ae199be"},"breadcrumb":{"@id":"https:\/\/espurna.cloud\/espurna\/noticias-desde-candanchu-segundo-dia-en-las-pistas#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/espurna.cloud\/espurna\/noticias-desde-candanchu-segundo-dia-en-las-pistas"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/espurna.cloud\/espurna\/noticias-desde-candanchu-segundo-dia-en-las-pistas#primaryimage","url":"http:\/\/www.espurna.org\/wp-content\/uploads\/2013\/02\/la-foto-53-300x168.jpg","contentUrl":"http:\/\/www.espurna.org\/wp-content\/uploads\/2013\/02\/la-foto-53-300x168.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/espurna.cloud\/espurna\/noticias-desde-candanchu-segundo-dia-en-las-pistas#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/espurna.cloud\/espurna\/"},{"@type":"ListItem","position":2,"name":"NOTICIAS DESDE CANDANCH\u00da! SEGUNDO D\u00cdA EN LAS PISTAS."}]},{"@type":"WebSite","@id":"https:\/\/espurna.cloud\/espurna\/#website","url":"https:\/\/espurna.cloud\/espurna\/","name":"Espurna.org","description":"Atenci\u00f3n integral a personas con discapacidad intelectual","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/espurna.cloud\/espurna\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/espurna.cloud\/espurna\/#\/schema\/person\/3e977e600ba60638d283f4767ae199be","name":"empleoespurna","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g","caption":"empleoespurna"},"url":"https:\/\/espurna.cloud\/espurna\/author\/empleoespurna"}]}},"_links":{"self":[{"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/posts\/770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/comments?post=770"}],"version-history":[{"count":0,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/posts\/770\/revisions"}],"wp:attachment":[{"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/media?parent=770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/categories?post=770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/tags?post=770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}