{"id":7720,"date":"2020-01-20T11:16:40","date_gmt":"2020-01-20T09:16:40","guid":{"rendered":"http:\/\/www.espurna.org\/?p=7720"},"modified":"2020-01-20T11:16:40","modified_gmt":"2020-01-20T09:16:40","slug":"las-tardes-de-extralaborales-son-geniales","status":"publish","type":"post","link":"https:\/\/espurna.cloud\/espurna\/las-tardes-de-extralaborales-son-geniales","title":{"rendered":"\u00a1Las tardes de extralaborales son geniales!"},"content":{"rendered":"<p>La semana pasada disfrutamos de muchas actividades culturales por Gandia. Visitamos el Museu Faller, la Plaza del Beato, la Biblioteca central, las estatuas de la familia Borgia y el \u00e1rbol de Rausell, lo pasamos \u00a1GENIAL!<\/p>\n<p><a href=\"http:\/\/www.espurna.org\/wp-content\/uploads\/2020\/01\/82192369_2676954955714397_786329922586017792_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7721\" src=\"http:\/\/www.espurna.org\/wp-content\/uploads\/2020\/01\/82192369_2676954955714397_786329922586017792_n-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/82192369_2676954955714397_786329922586017792_n-300x225.jpg 300w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/82192369_2676954955714397_786329922586017792_n-600x450.jpg 600w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/82192369_2676954955714397_786329922586017792_n-768x576.jpg 768w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/82192369_2676954955714397_786329922586017792_n-200x150.jpg 200w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/82192369_2676954955714397_786329922586017792_n-150x113.jpg 150w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/82192369_2676954955714397_786329922586017792_n.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"http:\/\/www.espurna.org\/wp-content\/uploads\/2020\/01\/82261671_2676955219047704_6480191285486419968_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7722\" src=\"http:\/\/www.espurna.org\/wp-content\/uploads\/2020\/01\/82261671_2676955219047704_6480191285486419968_n-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/82261671_2676955219047704_6480191285486419968_n-300x225.jpg 300w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/82261671_2676955219047704_6480191285486419968_n-600x450.jpg 600w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/82261671_2676955219047704_6480191285486419968_n-768x576.jpg 768w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/82261671_2676955219047704_6480191285486419968_n-200x150.jpg 200w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/82261671_2676955219047704_6480191285486419968_n-150x113.jpg 150w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/82261671_2676955219047704_6480191285486419968_n.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"http:\/\/www.espurna.org\/wp-content\/uploads\/2020\/01\/82297105_2676955225714370_4285054086279069696_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7724\" src=\"http:\/\/www.espurna.org\/wp-content\/uploads\/2020\/01\/82297105_2676955225714370_4285054086279069696_n-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/82297105_2676955225714370_4285054086279069696_n-225x300.jpg 225w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/82297105_2676955225714370_4285054086279069696_n-600x800.jpg 600w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/82297105_2676955225714370_4285054086279069696_n-113x150.jpg 113w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/82297105_2676955225714370_4285054086279069696_n.jpg 720w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"http:\/\/www.espurna.org\/wp-content\/uploads\/2020\/01\/82558766_2676955075714385_3327535748051107840_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7727\" src=\"http:\/\/www.espurna.org\/wp-content\/uploads\/2020\/01\/82558766_2676955075714385_3327535748051107840_n-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/82558766_2676955075714385_3327535748051107840_n-225x300.jpg 225w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/82558766_2676955075714385_3327535748051107840_n-600x800.jpg 600w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/82558766_2676955075714385_3327535748051107840_n-113x150.jpg 113w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/82558766_2676955075714385_3327535748051107840_n.jpg 720w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"http:\/\/www.espurna.org\/wp-content\/uploads\/2020\/01\/83096704_2676954839047742_7043373343235375104_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7729\" src=\"http:\/\/www.espurna.org\/wp-content\/uploads\/2020\/01\/83096704_2676954839047742_7043373343235375104_n-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/83096704_2676954839047742_7043373343235375104_n-225x300.jpg 225w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/83096704_2676954839047742_7043373343235375104_n-600x800.jpg 600w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/83096704_2676954839047742_7043373343235375104_n-113x150.jpg 113w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2020\/01\/83096704_2676954839047742_7043373343235375104_n.jpg 720w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La semana pasada disfrutamos de muchas actividades culturales por Gandia. Visitamos el Museu Faller, la Plaza del Beato, la Biblioteca central, las estatuas de la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7720","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1Las tardes de extralaborales son geniales! - Espurna.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/espurna.cloud\/espurna\/las-tardes-de-extralaborales-son-geniales\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Las tardes de extralaborales son geniales! - Espurna.org\" \/>\n<meta property=\"og:description\" content=\"La semana pasada disfrutamos de muchas actividades culturales por Gandia. Visitamos el Museu Faller, la Plaza del Beato, la Biblioteca central, las estatuas de la...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/espurna.cloud\/espurna\/las-tardes-de-extralaborales-son-geniales\" \/>\n<meta property=\"og:site_name\" content=\"Espurna.org\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-20T09:16:40+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.espurna.org\/wp-content\/uploads\/2020\/01\/82192369_2676954955714397_786329922586017792_n-300x225.jpg\" \/>\n<meta name=\"author\" content=\"empleoespurna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"empleoespurna\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/las-tardes-de-extralaborales-son-geniales#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/las-tardes-de-extralaborales-son-geniales\"},\"author\":{\"name\":\"empleoespurna\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#\\\/schema\\\/person\\\/3e977e600ba60638d283f4767ae199be\"},\"headline\":\"\u00a1Las tardes de extralaborales son geniales!\",\"datePublished\":\"2020-01-20T09:16:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/las-tardes-de-extralaborales-son-geniales\"},\"wordCount\":41,\"image\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/las-tardes-de-extralaborales-son-geniales#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.espurna.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/82192369_2676954955714397_786329922586017792_n-300x225.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/las-tardes-de-extralaborales-son-geniales\",\"url\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/las-tardes-de-extralaborales-son-geniales\",\"name\":\"\u00a1Las tardes de extralaborales son geniales! - Espurna.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/las-tardes-de-extralaborales-son-geniales#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/las-tardes-de-extralaborales-son-geniales#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.espurna.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/82192369_2676954955714397_786329922586017792_n-300x225.jpg\",\"datePublished\":\"2020-01-20T09:16:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#\\\/schema\\\/person\\\/3e977e600ba60638d283f4767ae199be\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/las-tardes-de-extralaborales-son-geniales#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/las-tardes-de-extralaborales-son-geniales\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/las-tardes-de-extralaborales-son-geniales#primaryimage\",\"url\":\"http:\\\/\\\/www.espurna.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/82192369_2676954955714397_786329922586017792_n-300x225.jpg\",\"contentUrl\":\"http:\\\/\\\/www.espurna.org\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/82192369_2676954955714397_786329922586017792_n-300x225.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/las-tardes-de-extralaborales-son-geniales#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Las tardes de extralaborales son geniales!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#website\",\"url\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/\",\"name\":\"Espurna.org\",\"description\":\"Atenci\u00f3n integral a personas con discapacidad intelectual\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#\\\/schema\\\/person\\\/3e977e600ba60638d283f4767ae199be\",\"name\":\"empleoespurna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g\",\"caption\":\"empleoespurna\"},\"url\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/author\\\/empleoespurna\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Las tardes de extralaborales son geniales! - Espurna.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/espurna.cloud\/espurna\/las-tardes-de-extralaborales-son-geniales","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Las tardes de extralaborales son geniales! - Espurna.org","og_description":"La semana pasada disfrutamos de muchas actividades culturales por Gandia. Visitamos el Museu Faller, la Plaza del Beato, la Biblioteca central, las estatuas de la...","og_url":"https:\/\/espurna.cloud\/espurna\/las-tardes-de-extralaborales-son-geniales","og_site_name":"Espurna.org","article_published_time":"2020-01-20T09:16:40+00:00","og_image":[{"url":"http:\/\/www.espurna.org\/wp-content\/uploads\/2020\/01\/82192369_2676954955714397_786329922586017792_n-300x225.jpg","type":"","width":"","height":""}],"author":"empleoespurna","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"empleoespurna"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/espurna.cloud\/espurna\/las-tardes-de-extralaborales-son-geniales#article","isPartOf":{"@id":"https:\/\/espurna.cloud\/espurna\/las-tardes-de-extralaborales-son-geniales"},"author":{"name":"empleoespurna","@id":"https:\/\/espurna.cloud\/espurna\/#\/schema\/person\/3e977e600ba60638d283f4767ae199be"},"headline":"\u00a1Las tardes de extralaborales son geniales!","datePublished":"2020-01-20T09:16:40+00:00","mainEntityOfPage":{"@id":"https:\/\/espurna.cloud\/espurna\/las-tardes-de-extralaborales-son-geniales"},"wordCount":41,"image":{"@id":"https:\/\/espurna.cloud\/espurna\/las-tardes-de-extralaborales-son-geniales#primaryimage"},"thumbnailUrl":"http:\/\/www.espurna.org\/wp-content\/uploads\/2020\/01\/82192369_2676954955714397_786329922586017792_n-300x225.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/espurna.cloud\/espurna\/las-tardes-de-extralaborales-son-geniales","url":"https:\/\/espurna.cloud\/espurna\/las-tardes-de-extralaborales-son-geniales","name":"\u00a1Las tardes de extralaborales son geniales! - Espurna.org","isPartOf":{"@id":"https:\/\/espurna.cloud\/espurna\/#website"},"primaryImageOfPage":{"@id":"https:\/\/espurna.cloud\/espurna\/las-tardes-de-extralaborales-son-geniales#primaryimage"},"image":{"@id":"https:\/\/espurna.cloud\/espurna\/las-tardes-de-extralaborales-son-geniales#primaryimage"},"thumbnailUrl":"http:\/\/www.espurna.org\/wp-content\/uploads\/2020\/01\/82192369_2676954955714397_786329922586017792_n-300x225.jpg","datePublished":"2020-01-20T09:16:40+00:00","author":{"@id":"https:\/\/espurna.cloud\/espurna\/#\/schema\/person\/3e977e600ba60638d283f4767ae199be"},"breadcrumb":{"@id":"https:\/\/espurna.cloud\/espurna\/las-tardes-de-extralaborales-son-geniales#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/espurna.cloud\/espurna\/las-tardes-de-extralaborales-son-geniales"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/espurna.cloud\/espurna\/las-tardes-de-extralaborales-son-geniales#primaryimage","url":"http:\/\/www.espurna.org\/wp-content\/uploads\/2020\/01\/82192369_2676954955714397_786329922586017792_n-300x225.jpg","contentUrl":"http:\/\/www.espurna.org\/wp-content\/uploads\/2020\/01\/82192369_2676954955714397_786329922586017792_n-300x225.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/espurna.cloud\/espurna\/las-tardes-de-extralaborales-son-geniales#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/espurna.cloud\/espurna\/"},{"@type":"ListItem","position":2,"name":"\u00a1Las tardes de extralaborales son geniales!"}]},{"@type":"WebSite","@id":"https:\/\/espurna.cloud\/espurna\/#website","url":"https:\/\/espurna.cloud\/espurna\/","name":"Espurna.org","description":"Atenci\u00f3n integral a personas con discapacidad intelectual","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/espurna.cloud\/espurna\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/espurna.cloud\/espurna\/#\/schema\/person\/3e977e600ba60638d283f4767ae199be","name":"empleoespurna","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g","caption":"empleoespurna"},"url":"https:\/\/espurna.cloud\/espurna\/author\/empleoespurna"}]}},"_links":{"self":[{"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/posts\/7720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/comments?post=7720"}],"version-history":[{"count":0,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/posts\/7720\/revisions"}],"wp:attachment":[{"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/media?parent=7720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/categories?post=7720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/tags?post=7720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}