{"id":9230,"date":"2021-05-18T16:33:56","date_gmt":"2021-05-18T14:33:56","guid":{"rendered":"https:\/\/www.espurna.org\/?p=9230"},"modified":"2021-05-21T12:25:52","modified_gmt":"2021-05-21T10:25:52","slug":"como-es-vivir-en-la-vivienda-tutelada-collverd","status":"publish","type":"post","link":"https:\/\/espurna.cloud\/espurna\/como-es-vivir-en-la-vivienda-tutelada-collverd","title":{"rendered":"\u00bfC\u00f3mo es vivir en la Vivienda Tutelada Collverd?"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][vc_column_text]\n<p style=\"text-align: justify;\">Bienvenidos a Collverd, nuestra casa y una de las viviendas tuteladas de Espurna en Gandia.<\/p>\n<p style=\"text-align: justify;\">Nosotras somos 7 chicas en nuestro piso, convivimos y disfrutamos juntas de nuestro d\u00eda a d\u00eda.<\/p>\n<p style=\"text-align: justify;\">Todas trabajamos en diferentes sitios, enclaves profesionales como el restaurante Boga, en limpieza, en algunas empresas o bien acudimos al centro ocupacional donde hay varios talleres como el de trencad\u00eds o cer\u00e1mica, donde hacemos encargos para particulares o para empresas.<\/p>\n<p style=\"text-align: justify;\">Al acabar nuestra jornada de trabajo nos espera nuestro educador y con su ayuda nos organizamos para mantener el orden y la limpieza de casa, cocinar, aprender a comer sano y a hacer deporte.<\/p>\n<p style=\"text-align: justify;\">Disfrutamos haciendo diferentes cosas juntas, como pasear, hacer deporte, ir a la biblioteca o despu\u00e9s de cenar ver una pel\u00edcula o alg\u00fan programa de cotilleo, que nos gusta enterarnos de todo.<\/p>\n<p style=\"text-align: justify;\">Los fines de semana hacemos rutas de senderismo, visitas a otros pueblos y vamos a la playa, tambi\u00e9n celebramos pascua, fallas\u2026 y por supuesto nuestros cumplea\u00f1os, para los que preparamos un picoteo y una tarta para soplar las velas con la cumplea\u00f1era. Todo aquello que nos permita no estar en contacto con mucha gente y seguir manteniendo los grupos burbuja que todo este a\u00f1o nos ha mantenido alejadas de nuestro \u201camigo\u201d el COVID.<\/p>\n<p style=\"text-align: justify;\">En definitiva, estar en una vivienda tutelada, nos permite aprender, compartir, convivir, adquirir valores y conocimientos que nos ayudan en nuestro d\u00eda a d\u00eda y lo mejor, sentir el cari\u00f1o de nuestro hogar.<\/p>\n[\/vc_column_text][vc_separator type=\u00bbnormal\u00bb][vc_column_text]\n<p style=\"text-align: right;\">Vivienda tutelada Collverd | Alba, Jenni, Eli, \u00c1ngela, Carla y Yolanda<\/p>\n[\/vc_column_text][vc_empty_space]<div class=\"qode-advanced-image-gallery  qode-aig-masonry-type qode-normal-space   \">\n\t<div class=\"qode-aig-inner qode-outer-space qode-aig-masonry qode-aig-four-columns\">\n\t\t<div class=\"qode-aig-grid-sizer\"><\/div>\n\t\t<div class=\"qode-aig-grid-gutter\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image qode-item-space qode-aig-default-masonry-item\">\n\t\t\t\t<div class=\"qode-aig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1732\" src=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-1.jpg 800w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-1-139x300.jpg 139w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-1-473x1024.jpg 473w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-1-768x1663.jpg 768w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-1-709x1536.jpg 709w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-1-700x1516.jpg 700w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-1-600x1299.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image qode-item-space qode-aig-default-masonry-item\">\n\t\t\t\t<div class=\"qode-aig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"756\" height=\"585\" src=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-2.jpg 756w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-2-300x232.jpg 300w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-2-700x542.jpg 700w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-2-600x464.jpg 600w\" sizes=\"auto, (max-width: 756px) 100vw, 756px\" \/>\t\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image qode-item-space qode-aig-default-masonry-item\">\n\t\t\t\t<div class=\"qode-aig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"462\" src=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-3.jpg 1000w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-3-300x139.jpg 300w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-3-768x355.jpg 768w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-3-700x323.jpg 700w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-3-600x277.jpg 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image qode-item-space qode-aig-default-masonry-item\">\n\t\t\t\t<div class=\"qode-aig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1732\" src=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-4.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-4.jpg 800w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-4-139x300.jpg 139w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-4-473x1024.jpg 473w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-4-768x1663.jpg 768w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-4-709x1536.jpg 709w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-4-700x1516.jpg 700w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-4-600x1299.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image qode-item-space qode-aig-default-masonry-item\">\n\t\t\t\t<div class=\"qode-aig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1182\" src=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-5-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-5-scaled.jpg 2560w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-5-300x139.jpg 300w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-5-1024x473.jpg 1024w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-5-768x355.jpg 768w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-5-1536x709.jpg 1536w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-5-2048x946.jpg 2048w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-5-700x323.jpg 700w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-5-600x277.jpg 600w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image qode-item-space qode-aig-default-masonry-item\">\n\t\t\t\t<div class=\"qode-aig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"462\" src=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-6.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-6.jpg 1000w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-6-300x139.jpg 300w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-6-768x355.jpg 768w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-6-700x323.jpg 700w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-6-600x277.jpg 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image qode-item-space qode-aig-default-masonry-item\">\n\t\t\t\t<div class=\"qode-aig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"462\" src=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-7.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-7.jpg 1000w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-7-300x139.jpg 300w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-7-768x355.jpg 768w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-7-700x323.jpg 700w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-7-600x277.jpg 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>[\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Bienvenidos a Collverd, nuestra casa y una de las viviendas tuteladas de Espurna en Gandia.<\/p>\n<p>Nosotras somos 7 chicas en nuestro piso, convivimos y disfrutamos juntas de nuestro d\u00eda a d\u00eda.<\/p>\n<p>Todas trabajamos en diferentes sitios, enclaves profesionales como el restaurante Boga, en limpieza, en algunas empresas como Smatex o Alehop o bien acudimos al centro ocupacional donde hay varios talleres como trencad\u00eds o cer\u00e1mica, donde hacemos encargos para particulares o para empresas.<\/p>\n","protected":false},"author":1,"featured_media":9235,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,13],"tags":[],"class_list":["post-9230","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-viviendas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfC\u00f3mo es vivir en la Vivienda Tutelada Collverd? - Espurna.org<\/title>\n<meta name=\"description\" content=\"Bienvenidos a Collverd, nuestra casa y una de las viviendas tuteladas de Espurna en Gandia.Nosotras somos 7 chicas en nuestro piso, convivimos y disfrutamos juntas de nuestro d\u00eda a d\u00eda.Todas trabajamos en diferentes sitios, enclaves profesionales como el restaurante Boga, en limpieza, en algunas empresas como Smatex o Alehop o bien acudimos al centro ocupacional donde hay varios talleres como trencad\u00eds o cer\u00e1mica, donde hacemos encargos para particulares o para empresas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/espurna.cloud\/espurna\/como-es-vivir-en-la-vivienda-tutelada-collverd\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo es vivir en la Vivienda Tutelada Collverd? - Espurna.org\" \/>\n<meta property=\"og:description\" content=\"Bienvenidos a Collverd, nuestra casa y una de las viviendas tuteladas de Espurna en Gandia.Nosotras somos 7 chicas en nuestro piso, convivimos y disfrutamos juntas de nuestro d\u00eda a d\u00eda.Todas trabajamos en diferentes sitios, enclaves profesionales como el restaurante Boga, en limpieza, en algunas empresas como Smatex o Alehop o bien acudimos al centro ocupacional donde hay varios talleres como trencad\u00eds o cer\u00e1mica, donde hacemos encargos para particulares o para empresas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/espurna.cloud\/espurna\/como-es-vivir-en-la-vivienda-tutelada-collverd\" \/>\n<meta property=\"og:site_name\" content=\"Espurna.org\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-18T14:33:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-21T10:25:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-5-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1182\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"empleoespurna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"empleoespurna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/como-es-vivir-en-la-vivienda-tutelada-collverd#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/como-es-vivir-en-la-vivienda-tutelada-collverd\"},\"author\":{\"name\":\"empleoespurna\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#\\\/schema\\\/person\\\/3e977e600ba60638d283f4767ae199be\"},\"headline\":\"\u00bfC\u00f3mo es vivir en la Vivienda Tutelada Collverd?\",\"datePublished\":\"2021-05-18T14:33:56+00:00\",\"dateModified\":\"2021-05-21T10:25:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/como-es-vivir-en-la-vivienda-tutelada-collverd\"},\"wordCount\":350,\"image\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/como-es-vivir-en-la-vivienda-tutelada-collverd#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/vivienda-tutelada-collverd-fundacio-espurna-5-scaled.jpg\",\"articleSection\":[\"Noticias\",\"Viviendas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/como-es-vivir-en-la-vivienda-tutelada-collverd\",\"url\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/como-es-vivir-en-la-vivienda-tutelada-collverd\",\"name\":\"\u00bfC\u00f3mo es vivir en la Vivienda Tutelada Collverd? - Espurna.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/como-es-vivir-en-la-vivienda-tutelada-collverd#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/como-es-vivir-en-la-vivienda-tutelada-collverd#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/vivienda-tutelada-collverd-fundacio-espurna-5-scaled.jpg\",\"datePublished\":\"2021-05-18T14:33:56+00:00\",\"dateModified\":\"2021-05-21T10:25:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#\\\/schema\\\/person\\\/3e977e600ba60638d283f4767ae199be\"},\"description\":\"Bienvenidos a Collverd, nuestra casa y una de las viviendas tuteladas de Espurna en Gandia.Nosotras somos 7 chicas en nuestro piso, convivimos y disfrutamos juntas de nuestro d\u00eda a d\u00eda.Todas trabajamos en diferentes sitios, enclaves profesionales como el restaurante Boga, en limpieza, en algunas empresas como Smatex o Alehop o bien acudimos al centro ocupacional donde hay varios talleres como trencad\u00eds o cer\u00e1mica, donde hacemos encargos para particulares o para empresas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/como-es-vivir-en-la-vivienda-tutelada-collverd#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/como-es-vivir-en-la-vivienda-tutelada-collverd\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/como-es-vivir-en-la-vivienda-tutelada-collverd#primaryimage\",\"url\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/vivienda-tutelada-collverd-fundacio-espurna-5-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/vivienda-tutelada-collverd-fundacio-espurna-5-scaled.jpg\",\"width\":2560,\"height\":1182},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/como-es-vivir-en-la-vivienda-tutelada-collverd#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo es vivir en la Vivienda Tutelada Collverd?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#website\",\"url\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/\",\"name\":\"Espurna.org\",\"description\":\"Atenci\u00f3n integral a personas con discapacidad intelectual\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#\\\/schema\\\/person\\\/3e977e600ba60638d283f4767ae199be\",\"name\":\"empleoespurna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g\",\"caption\":\"empleoespurna\"},\"url\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/author\\\/empleoespurna\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo es vivir en la Vivienda Tutelada Collverd? - Espurna.org","description":"Bienvenidos a Collverd, nuestra casa y una de las viviendas tuteladas de Espurna en Gandia.Nosotras somos 7 chicas en nuestro piso, convivimos y disfrutamos juntas de nuestro d\u00eda a d\u00eda.Todas trabajamos en diferentes sitios, enclaves profesionales como el restaurante Boga, en limpieza, en algunas empresas como Smatex o Alehop o bien acudimos al centro ocupacional donde hay varios talleres como trencad\u00eds o cer\u00e1mica, donde hacemos encargos para particulares o para empresas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/espurna.cloud\/espurna\/como-es-vivir-en-la-vivienda-tutelada-collverd","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo es vivir en la Vivienda Tutelada Collverd? - Espurna.org","og_description":"Bienvenidos a Collverd, nuestra casa y una de las viviendas tuteladas de Espurna en Gandia.Nosotras somos 7 chicas en nuestro piso, convivimos y disfrutamos juntas de nuestro d\u00eda a d\u00eda.Todas trabajamos en diferentes sitios, enclaves profesionales como el restaurante Boga, en limpieza, en algunas empresas como Smatex o Alehop o bien acudimos al centro ocupacional donde hay varios talleres como trencad\u00eds o cer\u00e1mica, donde hacemos encargos para particulares o para empresas.","og_url":"https:\/\/espurna.cloud\/espurna\/como-es-vivir-en-la-vivienda-tutelada-collverd","og_site_name":"Espurna.org","article_published_time":"2021-05-18T14:33:56+00:00","article_modified_time":"2021-05-21T10:25:52+00:00","og_image":[{"width":2560,"height":1182,"url":"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-5-scaled.jpg","type":"image\/jpeg"}],"author":"empleoespurna","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"empleoespurna","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/espurna.cloud\/espurna\/como-es-vivir-en-la-vivienda-tutelada-collverd#article","isPartOf":{"@id":"https:\/\/espurna.cloud\/espurna\/como-es-vivir-en-la-vivienda-tutelada-collverd"},"author":{"name":"empleoespurna","@id":"https:\/\/espurna.cloud\/espurna\/#\/schema\/person\/3e977e600ba60638d283f4767ae199be"},"headline":"\u00bfC\u00f3mo es vivir en la Vivienda Tutelada Collverd?","datePublished":"2021-05-18T14:33:56+00:00","dateModified":"2021-05-21T10:25:52+00:00","mainEntityOfPage":{"@id":"https:\/\/espurna.cloud\/espurna\/como-es-vivir-en-la-vivienda-tutelada-collverd"},"wordCount":350,"image":{"@id":"https:\/\/espurna.cloud\/espurna\/como-es-vivir-en-la-vivienda-tutelada-collverd#primaryimage"},"thumbnailUrl":"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-5-scaled.jpg","articleSection":["Noticias","Viviendas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/espurna.cloud\/espurna\/como-es-vivir-en-la-vivienda-tutelada-collverd","url":"https:\/\/espurna.cloud\/espurna\/como-es-vivir-en-la-vivienda-tutelada-collverd","name":"\u00bfC\u00f3mo es vivir en la Vivienda Tutelada Collverd? - Espurna.org","isPartOf":{"@id":"https:\/\/espurna.cloud\/espurna\/#website"},"primaryImageOfPage":{"@id":"https:\/\/espurna.cloud\/espurna\/como-es-vivir-en-la-vivienda-tutelada-collverd#primaryimage"},"image":{"@id":"https:\/\/espurna.cloud\/espurna\/como-es-vivir-en-la-vivienda-tutelada-collverd#primaryimage"},"thumbnailUrl":"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-5-scaled.jpg","datePublished":"2021-05-18T14:33:56+00:00","dateModified":"2021-05-21T10:25:52+00:00","author":{"@id":"https:\/\/espurna.cloud\/espurna\/#\/schema\/person\/3e977e600ba60638d283f4767ae199be"},"description":"Bienvenidos a Collverd, nuestra casa y una de las viviendas tuteladas de Espurna en Gandia.Nosotras somos 7 chicas en nuestro piso, convivimos y disfrutamos juntas de nuestro d\u00eda a d\u00eda.Todas trabajamos en diferentes sitios, enclaves profesionales como el restaurante Boga, en limpieza, en algunas empresas como Smatex o Alehop o bien acudimos al centro ocupacional donde hay varios talleres como trencad\u00eds o cer\u00e1mica, donde hacemos encargos para particulares o para empresas.","breadcrumb":{"@id":"https:\/\/espurna.cloud\/espurna\/como-es-vivir-en-la-vivienda-tutelada-collverd#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/espurna.cloud\/espurna\/como-es-vivir-en-la-vivienda-tutelada-collverd"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/espurna.cloud\/espurna\/como-es-vivir-en-la-vivienda-tutelada-collverd#primaryimage","url":"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-5-scaled.jpg","contentUrl":"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/vivienda-tutelada-collverd-fundacio-espurna-5-scaled.jpg","width":2560,"height":1182},{"@type":"BreadcrumbList","@id":"https:\/\/espurna.cloud\/espurna\/como-es-vivir-en-la-vivienda-tutelada-collverd#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/espurna.cloud\/espurna\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo es vivir en la Vivienda Tutelada Collverd?"}]},{"@type":"WebSite","@id":"https:\/\/espurna.cloud\/espurna\/#website","url":"https:\/\/espurna.cloud\/espurna\/","name":"Espurna.org","description":"Atenci\u00f3n integral a personas con discapacidad intelectual","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/espurna.cloud\/espurna\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/espurna.cloud\/espurna\/#\/schema\/person\/3e977e600ba60638d283f4767ae199be","name":"empleoespurna","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g","caption":"empleoespurna"},"url":"https:\/\/espurna.cloud\/espurna\/author\/empleoespurna"}]}},"_links":{"self":[{"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/posts\/9230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/comments?post=9230"}],"version-history":[{"count":0,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/posts\/9230\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/media\/9235"}],"wp:attachment":[{"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/media?parent=9230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/categories?post=9230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/tags?post=9230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}