{"id":9244,"date":"2021-05-21T12:00:08","date_gmt":"2021-05-21T10:00:08","guid":{"rendered":"https:\/\/www.espurna.org\/?p=9244"},"modified":"2021-05-21T12:25:01","modified_gmt":"2021-05-21T10:25:01","slug":"hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo","status":"publish","type":"post","link":"https:\/\/espurna.cloud\/espurna\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo","title":{"rendered":"Hasta el cuarenta de mayo no te quites el sayo"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][vc_column_text]\n<p style=\"text-align: justify;\">Bienvenidos a Collverd, nuestra casa y una de las viviendas tuteladas de Espurna en Gandia.<\/p>\n<p style=\"text-align: justify;\">Nosotras somos 7 chicas en nu Ya llega mayo, un mes donde el calor empieza a apretar, el sol est\u00e1 m\u00e1s presente y hay m\u00e1s horas de luz. Estamos en plena primavera, pero como dice el refr\u00e1n \u201chasta el cuarenta de mayo no quites el sayo\u201d; y como bien sabemos las chicas de la vivienda tutelada \u201cPonent\u201d \u00a0hay algunos d\u00edas que hace calor, otros fr\u00edo o igual nos llueve.<br \/>\nMayo es un mes colorido, cuando empiezan a florecer las flores, cuando a las chicas y los chicos de las viviendas tuteladas de Espurna nos encanta ir a pasear por todos los lugares, ya sea a la playa, a la monta\u00f1a o a visitar los distintos pueblos o ciudades de nuestros alrededores.<br \/>\nAunque la situaci\u00f3n sigue siendo complicada, y debemos hacer todo con mucha cautela por la COVID-19, hemos seguido visitando los distintos pueblos de las comarcas de alrededores, hemos visitado monumentos, fuentes, edificios; tambi\u00e9n hemos merendado y comido por las playas y merenderos de los pueblos y, hemos recorrido muchos kil\u00f3metros de rutas senderistas de nuestra querida provincia.<br \/>\nAdem\u00e1s, no quer\u00edamos dejar de mencionar dos d\u00edas festivos que son muy importantes para la familia Espurniana, que son:<br \/>\nEl d\u00eda del trabajador, el 1 de mayo; un d\u00eda festivo para reivindicar los derechos de los trabajadores, donde estamos muy orgullosas del trabajo y el esfuerzo que realizamos todos los que formamos Espurna.<br \/>\nY por otro lado el d\u00eda de la madre, el 2 de mayo. Este d\u00eda nos hemos acordado de nuestras madres\u00a0 y de nuestras compa\u00f1eras y monitoras que han sido madres, como Emilia, y durante el d\u00eda hemos hecho talleres y actividades con el fin de elaborar detalles para todas ellas.<br \/>\nPor \u00faltimo decir que estamos muy contentos y muy contentas por la llegada del calorcito\u00a0que nos permite disfrutar mas de las actividades y salidas que realizamos. estro piso, convivimos y disfrutamos juntas de nuestro d\u00eda a d\u00eda.<\/p>\n<p style=\"text-align: justify;\">Todas trabajamos en diferentes sitios, enclaves profesionales como el restaurante Boga, en limpieza, en algunas empresas o bien acudimos al centro ocupacional donde hay varios talleres como el de trencad\u00eds o cer\u00e1mica, donde hacemos encargos para particulares o para empresas.<\/p>\n<p style=\"text-align: justify;\">Al acabar nuestra jornada de trabajo nos espera nuestro educador y con su ayuda nos organizamos para mantener el orden y la limpieza de casa, cocinar, aprender a comer sano y a hacer deporte.<\/p>\n<p style=\"text-align: justify;\">Disfrutamos haciendo diferentes cosas juntas, como pasear, hacer deporte, ir a la biblioteca o despu\u00e9s de cenar ver una pel\u00edcula o alg\u00fan programa de cotilleo, que nos gusta enterarnos de todo.<\/p>\n<p style=\"text-align: justify;\">Los fines de semana hacemos rutas de senderismo, visitas a otros pueblos y vamos a la playa, tambi\u00e9n celebramos pascua, fallas\u2026 y por supuesto nuestros cumplea\u00f1os, para los que preparamos un picoteo y una tarta para soplar las velas con la cumplea\u00f1era. Todo aquello que nos permita no estar en contacto con mucha gente y seguir manteniendo los grupos burbuja que todo este a\u00f1o nos ha mantenido alejadas de nuestro \u201camigo\u201d el COVID.<\/p>\n<p style=\"text-align: justify;\">En definitiva, estar en una vivienda tutelada, nos permite aprender, compartir, convivir, adquirir valores y conocimientos que nos ayudan en nuestro d\u00eda a d\u00eda y lo mejor, sentir el cari\u00f1o de nuestro hogar.<\/p>\n[\/vc_column_text][vc_separator type=\u00bbnormal\u00bb][vc_column_text]\n<p style=\"text-align: right;\">Vivienda tutelada Ponent | Emilia, Carmen, Mari Luz y Marisa<\/p>\n[\/vc_column_text][vc_empty_space]<div class=\"qode-advanced-image-gallery  qode-aig-masonry-type qode-normal-space   \">\n\t<div class=\"qode-aig-inner qode-outer-space qode-aig-masonry qode-aig-four-columns\">\n\t\t<div class=\"qode-aig-grid-sizer\"><\/div>\n\t\t<div class=\"qode-aig-grid-gutter\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image qode-item-space qode-aig-default-masonry-item\">\n\t\t\t\t<div class=\"qode-aig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1333\" src=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/IMG_20210508_185019.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/IMG_20210508_185019.jpg 1000w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/IMG_20210508_185019-225x300.jpg 225w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/IMG_20210508_185019-768x1024.jpg 768w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/IMG_20210508_185019-600x800.jpg 600w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/IMG_20210508_185019-700x933.jpg 700w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image qode-item-space qode-aig-default-masonry-item\">\n\t\t\t\t<div class=\"qode-aig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/IMG_20210509_151831.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/IMG_20210509_151831.jpg 1000w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/IMG_20210509_151831-300x225.jpg 300w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/IMG_20210509_151831-768x576.jpg 768w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/IMG_20210509_151831-800x600.jpg 800w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/IMG_20210509_151831-700x525.jpg 700w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/IMG_20210509_151831-600x450.jpg 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image qode-item-space qode-aig-default-masonry-item\">\n\t\t\t\t<div class=\"qode-aig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/thumbnail_WhatsApp-Image-2021-05-04-at-18.08.53.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/thumbnail_WhatsApp-Image-2021-05-04-at-18.08.53.jpg 960w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/thumbnail_WhatsApp-Image-2021-05-04-at-18.08.53-225x300.jpg 225w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/thumbnail_WhatsApp-Image-2021-05-04-at-18.08.53-768x1024.jpg 768w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/thumbnail_WhatsApp-Image-2021-05-04-at-18.08.53-600x800.jpg 600w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/thumbnail_WhatsApp-Image-2021-05-04-at-18.08.53-700x933.jpg 700w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image qode-item-space qode-aig-default-masonry-item\">\n\t\t\t\t<div class=\"qode-aig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/thumbnail_WhatsApp-Image-2021-05-04-at-18.10.11.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/thumbnail_WhatsApp-Image-2021-05-04-at-18.10.11.jpg 960w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/thumbnail_WhatsApp-Image-2021-05-04-at-18.10.11-225x300.jpg 225w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/thumbnail_WhatsApp-Image-2021-05-04-at-18.10.11-768x1024.jpg 768w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/thumbnail_WhatsApp-Image-2021-05-04-at-18.10.11-600x800.jpg 600w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/thumbnail_WhatsApp-Image-2021-05-04-at-18.10.11-700x933.jpg 700w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image qode-item-space qode-aig-default-masonry-item\">\n\t\t\t\t<div class=\"qode-aig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1333\" src=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-04-at-18.05.39.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-04-at-18.05.39.jpeg 1000w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-04-at-18.05.39-225x300.jpeg 225w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-04-at-18.05.39-768x1024.jpeg 768w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-04-at-18.05.39-600x800.jpeg 600w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-04-at-18.05.39-700x933.jpeg 700w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image qode-item-space qode-aig-default-masonry-item\">\n\t\t\t\t<div class=\"qode-aig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1333\" src=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-04-at-18.06.18.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-04-at-18.06.18.jpeg 1000w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-04-at-18.06.18-225x300.jpeg 225w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-04-at-18.06.18-768x1024.jpeg 768w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-04-at-18.06.18-600x800.jpeg 600w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-04-at-18.06.18-700x933.jpeg 700w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"qode-aig-image qode-item-space qode-aig-default-masonry-item\">\n\t\t\t\t<div class=\"qode-aig-image-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1333\" src=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-04-at-18.11.09.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-04-at-18.11.09.jpeg 1000w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-04-at-18.11.09-225x300.jpeg 225w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-04-at-18.11.09-768x1024.jpeg 768w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-04-at-18.11.09-600x800.jpeg 600w, https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-04-at-18.11.09-700x933.jpeg 700w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t<span class=\"aig-gallery-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>[\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Ya llega mayo, un mes donde el calor empieza a apretar, el sol est\u00e1 m\u00e1s presente y hay m\u00e1s horas de luz. Estamos en plena primavera, pero como dice el refr\u00e1n \u201chasta el cuarenta de mayo no quites el sayo\u201d; y como bien sabemos las chicas de la vivienda tutelada \u201cPonent\u201d \u00a0hay algunos d\u00edas que hace calor, otros fr\u00edo o igual nos llueve. <\/p>\n","protected":false},"author":1,"featured_media":9246,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,13],"tags":[],"class_list":["post-9244","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-viviendas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hasta el cuarenta de mayo no te quites el sayo - Espurna.org<\/title>\n<meta name=\"description\" content=\"Ya llega mayo, un mes donde el calor empieza a apretar, el sol est\u00e1 m\u00e1s presente y hay m\u00e1s horas de luz. Estamos en plena primavera, pero como dice el refr\u00e1n \u201chasta el cuarenta de mayo no quites el sayo\u201d; y como bien sabemos las chicas de la vivienda tutelada \u201cPonent\u201d \u00a0hay algunos d\u00edas que hace calor, otros fr\u00edo o igual nos llueve.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/espurna.cloud\/espurna\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hasta el cuarenta de mayo no te quites el sayo - Espurna.org\" \/>\n<meta property=\"og:description\" content=\"Ya llega mayo, un mes donde el calor empieza a apretar, el sol est\u00e1 m\u00e1s presente y hay m\u00e1s horas de luz. Estamos en plena primavera, pero como dice el refr\u00e1n \u201chasta el cuarenta de mayo no quites el sayo\u201d; y como bien sabemos las chicas de la vivienda tutelada \u201cPonent\u201d \u00a0hay algunos d\u00edas que hace calor, otros fr\u00edo o igual nos llueve.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/espurna.cloud\/espurna\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo\" \/>\n<meta property=\"og:site_name\" content=\"Espurna.org\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-21T10:00:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-21T10:25:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/IMG_20210509_151831.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"empleoespurna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"empleoespurna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo\"},\"author\":{\"name\":\"empleoespurna\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#\\\/schema\\\/person\\\/3e977e600ba60638d283f4767ae199be\"},\"headline\":\"Hasta el cuarenta de mayo no te quites el sayo\",\"datePublished\":\"2021-05-21T10:00:08+00:00\",\"dateModified\":\"2021-05-21T10:25:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo\"},\"wordCount\":670,\"image\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/IMG_20210509_151831.jpg\",\"articleSection\":[\"Noticias\",\"Viviendas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo\",\"url\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo\",\"name\":\"Hasta el cuarenta de mayo no te quites el sayo - Espurna.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/IMG_20210509_151831.jpg\",\"datePublished\":\"2021-05-21T10:00:08+00:00\",\"dateModified\":\"2021-05-21T10:25:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#\\\/schema\\\/person\\\/3e977e600ba60638d283f4767ae199be\"},\"description\":\"Ya llega mayo, un mes donde el calor empieza a apretar, el sol est\u00e1 m\u00e1s presente y hay m\u00e1s horas de luz. Estamos en plena primavera, pero como dice el refr\u00e1n \u201chasta el cuarenta de mayo no quites el sayo\u201d; y como bien sabemos las chicas de la vivienda tutelada \u201cPonent\u201d \u00a0hay algunos d\u00edas que hace calor, otros fr\u00edo o igual nos llueve.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo#primaryimage\",\"url\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/IMG_20210509_151831.jpg\",\"contentUrl\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/IMG_20210509_151831.jpg\",\"width\":1000,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hasta el cuarenta de mayo no te quites el sayo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#website\",\"url\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/\",\"name\":\"Espurna.org\",\"description\":\"Atenci\u00f3n integral a personas con discapacidad intelectual\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/#\\\/schema\\\/person\\\/3e977e600ba60638d283f4767ae199be\",\"name\":\"empleoespurna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g\",\"caption\":\"empleoespurna\"},\"url\":\"https:\\\/\\\/espurna.cloud\\\/espurna\\\/author\\\/empleoespurna\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hasta el cuarenta de mayo no te quites el sayo - Espurna.org","description":"Ya llega mayo, un mes donde el calor empieza a apretar, el sol est\u00e1 m\u00e1s presente y hay m\u00e1s horas de luz. Estamos en plena primavera, pero como dice el refr\u00e1n \u201chasta el cuarenta de mayo no quites el sayo\u201d; y como bien sabemos las chicas de la vivienda tutelada \u201cPonent\u201d \u00a0hay algunos d\u00edas que hace calor, otros fr\u00edo o igual nos llueve.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/espurna.cloud\/espurna\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo","og_locale":"es_ES","og_type":"article","og_title":"Hasta el cuarenta de mayo no te quites el sayo - Espurna.org","og_description":"Ya llega mayo, un mes donde el calor empieza a apretar, el sol est\u00e1 m\u00e1s presente y hay m\u00e1s horas de luz. Estamos en plena primavera, pero como dice el refr\u00e1n \u201chasta el cuarenta de mayo no quites el sayo\u201d; y como bien sabemos las chicas de la vivienda tutelada \u201cPonent\u201d \u00a0hay algunos d\u00edas que hace calor, otros fr\u00edo o igual nos llueve.","og_url":"https:\/\/espurna.cloud\/espurna\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo","og_site_name":"Espurna.org","article_published_time":"2021-05-21T10:00:08+00:00","article_modified_time":"2021-05-21T10:25:01+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/IMG_20210509_151831.jpg","type":"image\/jpeg"}],"author":"empleoespurna","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"empleoespurna","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/espurna.cloud\/espurna\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo#article","isPartOf":{"@id":"https:\/\/espurna.cloud\/espurna\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo"},"author":{"name":"empleoespurna","@id":"https:\/\/espurna.cloud\/espurna\/#\/schema\/person\/3e977e600ba60638d283f4767ae199be"},"headline":"Hasta el cuarenta de mayo no te quites el sayo","datePublished":"2021-05-21T10:00:08+00:00","dateModified":"2021-05-21T10:25:01+00:00","mainEntityOfPage":{"@id":"https:\/\/espurna.cloud\/espurna\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo"},"wordCount":670,"image":{"@id":"https:\/\/espurna.cloud\/espurna\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo#primaryimage"},"thumbnailUrl":"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/IMG_20210509_151831.jpg","articleSection":["Noticias","Viviendas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/espurna.cloud\/espurna\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo","url":"https:\/\/espurna.cloud\/espurna\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo","name":"Hasta el cuarenta de mayo no te quites el sayo - Espurna.org","isPartOf":{"@id":"https:\/\/espurna.cloud\/espurna\/#website"},"primaryImageOfPage":{"@id":"https:\/\/espurna.cloud\/espurna\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo#primaryimage"},"image":{"@id":"https:\/\/espurna.cloud\/espurna\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo#primaryimage"},"thumbnailUrl":"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/IMG_20210509_151831.jpg","datePublished":"2021-05-21T10:00:08+00:00","dateModified":"2021-05-21T10:25:01+00:00","author":{"@id":"https:\/\/espurna.cloud\/espurna\/#\/schema\/person\/3e977e600ba60638d283f4767ae199be"},"description":"Ya llega mayo, un mes donde el calor empieza a apretar, el sol est\u00e1 m\u00e1s presente y hay m\u00e1s horas de luz. Estamos en plena primavera, pero como dice el refr\u00e1n \u201chasta el cuarenta de mayo no quites el sayo\u201d; y como bien sabemos las chicas de la vivienda tutelada \u201cPonent\u201d \u00a0hay algunos d\u00edas que hace calor, otros fr\u00edo o igual nos llueve.","breadcrumb":{"@id":"https:\/\/espurna.cloud\/espurna\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/espurna.cloud\/espurna\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/espurna.cloud\/espurna\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo#primaryimage","url":"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/IMG_20210509_151831.jpg","contentUrl":"https:\/\/espurna.cloud\/espurna\/wp-content\/uploads\/2021\/05\/IMG_20210509_151831.jpg","width":1000,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/espurna.cloud\/espurna\/hasta-el-cuarenta-de-mayo-no-te-quites-el-sayo#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/espurna.cloud\/espurna\/"},{"@type":"ListItem","position":2,"name":"Hasta el cuarenta de mayo no te quites el sayo"}]},{"@type":"WebSite","@id":"https:\/\/espurna.cloud\/espurna\/#website","url":"https:\/\/espurna.cloud\/espurna\/","name":"Espurna.org","description":"Atenci\u00f3n integral a personas con discapacidad intelectual","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/espurna.cloud\/espurna\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/espurna.cloud\/espurna\/#\/schema\/person\/3e977e600ba60638d283f4767ae199be","name":"empleoespurna","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/42c2e1c07579b2627711fbb797008ed9dfffe43c66adc8767b118eb7e3ae739d?s=96&d=mm&r=g","caption":"empleoespurna"},"url":"https:\/\/espurna.cloud\/espurna\/author\/empleoespurna"}]}},"_links":{"self":[{"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/posts\/9244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/comments?post=9244"}],"version-history":[{"count":0,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/posts\/9244\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/media\/9246"}],"wp:attachment":[{"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/media?parent=9244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/categories?post=9244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espurna.cloud\/espurna\/wp-json\/wp\/v2\/tags?post=9244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}